{"id":69,"count":4,"description":"","link":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/","name":"BAIXA TEMPERATURA","slug":"baixa-temperatura","taxonomy":"product_cat","parent":94,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plico | BAIXA TEMPERATURA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plico | BAIXA TEMPERATURA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/\" \/>\n<meta property=\"og:site_name\" content=\"Plico\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plico.es\/wp-content\/uploads\/2022\/12\/BODEGON-CINTA-PINTAR2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/categoria-producto\\\/termofusivel\\\/baixa-temperatura\\\/\",\"url\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/categoria-producto\\\/termofusivel\\\/baixa-temperatura\\\/\",\"name\":\"Plico | BAIXA TEMPERATURA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/categoria-producto\\\/termofusivel\\\/baixa-temperatura\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/categoria-producto\\\/termofusivel\\\/baixa-temperatura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termofus\u00edvel\",\"item\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/categoria-producto\\\/termofusivel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAIXA TEMPERATURA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/\",\"name\":\"Plico\",\"description\":\"Expertos en Manualidades\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Productos L\u00edderes Comercializados, S.A.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/#organization\",\"name\":\"Plico\",\"alternateName\":\"Productos L\u00edderes Comercializados, S.A.\",\"url\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plico.es\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo_plico.png\",\"contentUrl\":\"https:\\\/\\\/www.plico.es\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo_plico.png\",\"width\":400,\"height\":185,\"caption\":\"Plico\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plico.es\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/plico2017\\\/\",\"https:\\\/\\\/www.instagram.com\\\/plico_es\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCC1ygHF4QAP-CTLDlHMLs7g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plico | BAIXA TEMPERATURA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/","og_locale":"pt_PT","og_type":"article","og_title":"Plico | BAIXA TEMPERATURA","og_url":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/","og_site_name":"Plico","og_image":[{"width":2560,"height":2288,"url":"https:\/\/www.plico.es\/wp-content\/uploads\/2022\/12\/BODEGON-CINTA-PINTAR2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/","url":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/","name":"Plico | BAIXA TEMPERATURA","isPartOf":{"@id":"https:\/\/www.plico.es\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/baixa-temperatura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.plico.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Termofus\u00edvel","item":"https:\/\/www.plico.es\/pt-pt\/categoria-producto\/termofusivel\/"},{"@type":"ListItem","position":3,"name":"BAIXA TEMPERATURA"}]},{"@type":"WebSite","@id":"https:\/\/www.plico.es\/pt-pt\/#website","url":"https:\/\/www.plico.es\/pt-pt\/","name":"Plico","description":"Expertos en Manualidades","publisher":{"@id":"https:\/\/www.plico.es\/pt-pt\/#organization"},"alternateName":"Productos L\u00edderes Comercializados, S.A.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plico.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.plico.es\/pt-pt\/#organization","name":"Plico","alternateName":"Productos L\u00edderes Comercializados, S.A.","url":"https:\/\/www.plico.es\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.plico.es\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.plico.es\/wp-content\/uploads\/2022\/05\/logo_plico.png","contentUrl":"https:\/\/www.plico.es\/wp-content\/uploads\/2022\/05\/logo_plico.png","width":400,"height":185,"caption":"Plico"},"image":{"@id":"https:\/\/www.plico.es\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/plico2017\/","https:\/\/www.instagram.com\/plico_es\/","https:\/\/www.youtube.com\/channel\/UCC1ygHF4QAP-CTLDlHMLs7g"]}]}},"_links":{"self":[{"href":"https:\/\/www.plico.es\/pt-pt\/wp-json\/wp\/v2\/product_cat\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plico.es\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.plico.es\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.plico.es\/pt-pt\/wp-json\/wp\/v2\/product_cat\/94"}],"wp:post_type":[{"href":"https:\/\/www.plico.es\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}